	{"id":261,"count":5,"description":"<b>Los mejores para cualquier prueba.<\/b>\r\n\r\n<span style=\"font-weight: 400\">Al igual que todos los dem\u00e1s productos desarrollados por Fieldpiece, nuestras soluciones de cables de prueba han sido espec\u00edficamente dise\u00f1adas para ofrecer el m\u00e1ximo rendimiento en el campo y son exactas, duraderas y vers\u00e1tiles.\u00a0 Nuestros cables de prueba de silicona mantienen su flexibilidad en condiciones de fr\u00edo extremo, son f\u00e1ciles de utilizar y ofrecen una alta resistencia al calor.<\/span>","link":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/","name":"Cables","slug":"leads-es-2","taxonomy":"product_cat","parent":160,"meta":[],"menu_order":32,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cables Archives - Fieldpiece Instruments<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cables Archives - Fieldpiece Instruments\" \/>\n<meta property=\"og:description\" content=\"Los mejores para cualquier prueba. Al igual que todos los dem\u00e1s productos desarrollados por Fieldpiece, nuestras soluciones de cables de prueba han sido espec\u00edficamente dise\u00f1adas para ofrecer el m\u00e1ximo rendimiento en el campo y son exactas, duraderas y vers\u00e1tiles.\u00a0 Nuestros cables de prueba de silicona mantienen su flexibilidad en condiciones de fr\u00edo extremo, son f\u00e1ciles de utilizar y ofrecen una alta resistencia al calor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fieldpiece Instruments\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/categoria-producto\\\/other-es-2\\\/leads-es-2\\\/\",\"url\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/categoria-producto\\\/other-es-2\\\/leads-es-2\\\/\",\"name\":\"Cables Archives - Fieldpiece Instruments\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/categoria-producto\\\/other-es-2\\\/leads-es-2\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/categoria-producto\\\/other-es-2\\\/leads-es-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otros\",\"item\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/categoria-producto\\\/other-es-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/\",\"name\":\"Fieldpiece Instruments\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/#organization\",\"name\":\"Fieldpiece Instruments\",\"url\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.fieldpiece.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logos-490x358-1.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.fieldpiece.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logos-490x358-1.jpg\",\"width\":490,\"height\":358,\"caption\":\"Fieldpiece Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fieldpiece.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cables Archives - Fieldpiece Instruments","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/","og_locale":"es_ES","og_type":"article","og_title":"Cables Archives - Fieldpiece Instruments","og_description":"Los mejores para cualquier prueba. Al igual que todos los dem\u00e1s productos desarrollados por Fieldpiece, nuestras soluciones de cables de prueba han sido espec\u00edficamente dise\u00f1adas para ofrecer el m\u00e1ximo rendimiento en el campo y son exactas, duraderas y vers\u00e1tiles.\u00a0 Nuestros cables de prueba de silicona mantienen su flexibilidad en condiciones de fr\u00edo extremo, son f\u00e1ciles de utilizar y ofrecen una alta resistencia al calor.","og_url":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/","og_site_name":"Fieldpiece Instruments","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/","url":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/","name":"Cables Archives - Fieldpiece Instruments","isPartOf":{"@id":"https:\/\/www.fieldpiece.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/leads-es-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fieldpiece.com\/es\/"},{"@type":"ListItem","position":2,"name":"Otros","item":"https:\/\/www.fieldpiece.com\/es\/categoria-producto\/other-es-2\/"},{"@type":"ListItem","position":3,"name":"Cables"}]},{"@type":"WebSite","@id":"https:\/\/www.fieldpiece.com\/es\/#website","url":"https:\/\/www.fieldpiece.com\/es\/","name":"Fieldpiece Instruments","description":"","publisher":{"@id":"https:\/\/www.fieldpiece.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fieldpiece.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fieldpiece.com\/es\/#organization","name":"Fieldpiece Instruments","url":"https:\/\/www.fieldpiece.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fieldpiece.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/resources.fieldpiece.com\/wp-content\/uploads\/2021\/02\/Logos-490x358-1.jpg","contentUrl":"https:\/\/resources.fieldpiece.com\/wp-content\/uploads\/2021\/02\/Logos-490x358-1.jpg","width":490,"height":358,"caption":"Fieldpiece Instruments"},"image":{"@id":"https:\/\/www.fieldpiece.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fieldpiece.com\/es\/wp-json\/wp\/v2\/product_cat\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fieldpiece.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.fieldpiece.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.fieldpiece.com\/es\/wp-json\/wp\/v2\/product_cat\/160"}],"wp:post_type":[{"href":"https:\/\/www.fieldpiece.com\/es\/wp-json\/wp\/v2\/product?product_cat=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}